{"id":373,"date":"2020-02-13T13:54:07","date_gmt":"2020-02-13T18:54:07","guid":{"rendered":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/?p=373"},"modified":"2020-02-13T13:54:08","modified_gmt":"2020-02-13T18:54:08","slug":"thursday-feb-13th-2020","status":"publish","type":"post","link":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/2020\/02\/13\/thursday-feb-13th-2020\/","title":{"rendered":"Thursday Feb 13th 2020"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"638\" height=\"371\" src=\"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-content\/uploads\/sites\/3045\/2020\/02\/image-24.jpg\" alt=\"\" class=\"wp-image-374\" srcset=\"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-content\/uploads\/sites\/3045\/2020\/02\/image-24.jpg 638w, https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-content\/uploads\/sites\/3045\/2020\/02\/image-24-300x174.png 300w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"655\" height=\"370\" src=\"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-content\/uploads\/sites\/3045\/2020\/02\/image-25.jpg\" alt=\"\" class=\"wp-image-375\" srcset=\"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-content\/uploads\/sites\/3045\/2020\/02\/image-25.jpg 655w, https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-content\/uploads\/sites\/3045\/2020\/02\/image-25-300x169.png 300w\" sizes=\"auto, (max-width: 655px) 100vw, 655px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2051,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-373","post","type-post","status-publish","format-standard","hentry","category-blogs"],"_links":{"self":[{"href":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-json\/wp\/v2\/posts\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-json\/wp\/v2\/users\/2051"}],"replies":[{"embeddable":true,"href":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-json\/wp\/v2\/comments?post=373"}],"version-history":[{"count":0,"href":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-json\/wp\/v2\/posts\/373\/revisions"}],"wp:attachment":[{"href":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-json\/wp\/v2\/media?parent=373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-json\/wp\/v2\/categories?post=373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iblog.dearbornschools.org\/iloveenvironmentalscience\/wp-json\/wp\/v2\/tags?post=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}